{"id":20383,"date":"2023-05-28T01:09:35","date_gmt":"2023-05-28T05:09:35","guid":{"rendered":"https:\/\/fleuretbonbon.com\/?post_type=product&#038;p=20383"},"modified":"2025-10-01T21:11:39","modified_gmt":"2025-10-02T01:11:39","slug":"aerienne-mer","status":"publish","type":"product","link":"https:\/\/fleuretbonbon.com\/en\/produit\/aerienne-mer\/","title":{"rendered":"Ae\u0301rienne Mer"},"content":{"rendered":"<p>A\u00e9rienne<\/p>\n<p>74% Baby Suri Alpaca, 26% Silk<br \/>\n328 yards (300 m) \/ 50 g<br \/>\n1 ply<br \/>\nDelicate, incredibly soft, light and airy yarn. Can be knitted alone, in double, or in combination with another thread.<br \/>\nCan replace mohair.<\/p>\n<p>Hand-dyed yarn in small batches. All efforts had been made to ensure that the skeins are as similar as possible. There may be differences, however. This is why it is recommended to alternate skeins for optimal results when more than one is used.<\/p>\n<p>All efforts had also been made to represent the colors as accurately as possible. However, colors may vary from one screen to another.<\/p>\n<p>Your project is precious. It is recommended to wash it by hand with a mild soap and lay it flat to dry.<\/p>\n<p>Each skein is rinsed multiple times. However, it could happen that bleeding occurs, especially with the first washes.<\/p>\n<p>The skeins were twisted and tagged in a house with cats.<\/p>","protected":false},"excerpt":{"rendered":"<p>The price is in Canadian dollars.<\/p>\n","protected":false},"featured_media":20398,"template":"","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ae\u0301rienne Mer - Fleur et Bonbon<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ae\u0301rienne Mer - Fleur et Bonbon\" \/>\n<meta property=\"og:description\" content=\"[:fr]Le prix est en dollars canadiens.[:en]The price is in Canadian dollars.[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/\" \/>\n<meta property=\"og:site_name\" content=\"Fleur et Bonbon\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T01:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2023\/05\/Aerienne-Mer-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1721\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fleuretbonbon.com\/fr\/#organization\",\"name\":\"Fleur et Bonbon\",\"url\":\"https:\/\/fleuretbonbon.com\/fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fleuretbonbon.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2019\/12\/Logo-final2.jpg\",\"contentUrl\":\"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2019\/12\/Logo-final2.jpg\",\"width\":1149,\"height\":155,\"caption\":\"Fleur et Bonbon\"},\"image\":{\"@id\":\"https:\/\/fleuretbonbon.com\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fleuretbonbon.com\/fr\/#website\",\"url\":\"https:\/\/fleuretbonbon.com\/fr\/\",\"name\":\"Fleur et Bonbon\",\"description\":\"Hand-dyed yarn - Knitting patterns\",\"publisher\":{\"@id\":\"https:\/\/fleuretbonbon.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fleuretbonbon.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#primaryimage\",\"url\":\"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2023\/05\/Aerienne-Mer-1-scaled.jpg\",\"contentUrl\":\"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2023\/05\/Aerienne-Mer-1-scaled.jpg\",\"width\":1721,\"height\":2560},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#webpage\",\"url\":\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/\",\"name\":\"Ae\u0301rienne Mer - Fleur et Bonbon\",\"isPartOf\":{\"@id\":\"https:\/\/fleuretbonbon.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#primaryimage\"},\"datePublished\":\"2023-05-28T05:09:35+00:00\",\"dateModified\":\"2025-10-02T01:11:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fleuretbonbon.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/fleuretbonbon.com\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[:fr]A\u00e9rienne Mer[:en]Ae\u0301rienne Mer[:]\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ae\u0301rienne Mer - Fleur et Bonbon","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Ae\u0301rienne Mer - Fleur et Bonbon","og_description":"[:fr]Le prix est en dollars canadiens.[:en]The price is in Canadian dollars.[:]","og_url":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/","og_site_name":"Fleur et Bonbon","article_modified_time":"2025-10-02T01:11:39+00:00","og_image":[{"width":1721,"height":2560,"url":"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2023\/05\/Aerienne-Mer-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fleuretbonbon.com\/fr\/#organization","name":"Fleur et Bonbon","url":"https:\/\/fleuretbonbon.com\/fr\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fleuretbonbon.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2019\/12\/Logo-final2.jpg","contentUrl":"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2019\/12\/Logo-final2.jpg","width":1149,"height":155,"caption":"Fleur et Bonbon"},"image":{"@id":"https:\/\/fleuretbonbon.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/fleuretbonbon.com\/fr\/#website","url":"https:\/\/fleuretbonbon.com\/fr\/","name":"Fleur et Bonbon","description":"Hand-dyed yarn - Knitting patterns","publisher":{"@id":"https:\/\/fleuretbonbon.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fleuretbonbon.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#primaryimage","url":"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2023\/05\/Aerienne-Mer-1-scaled.jpg","contentUrl":"https:\/\/fleuretbonbon.com\/wp-content\/uploads\/2023\/05\/Aerienne-Mer-1-scaled.jpg","width":1721,"height":2560},{"@type":"WebPage","@id":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#webpage","url":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/","name":"Ae\u0301rienne Mer - Fleur et Bonbon","isPartOf":{"@id":"https:\/\/fleuretbonbon.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#primaryimage"},"datePublished":"2023-05-28T05:09:35+00:00","dateModified":"2025-10-02T01:11:39+00:00","breadcrumb":{"@id":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fleuretbonbon.com\/produit\/aerienne-mer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fleuretbonbon.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/fleuretbonbon.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"[:fr]A\u00e9rienne Mer[:en]Ae\u0301rienne Mer[:]"}]}]}},"_links":{"self":[{"href":"https:\/\/fleuretbonbon.com\/en\/wp-json\/wp\/v2\/product\/20383"}],"collection":[{"href":"https:\/\/fleuretbonbon.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fleuretbonbon.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fleuretbonbon.com\/en\/wp-json\/wp\/v2\/media\/20398"}],"wp:attachment":[{"href":"https:\/\/fleuretbonbon.com\/en\/wp-json\/wp\/v2\/media?parent=20383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}